{"id":7238,"date":"2023-10-06T10:47:38","date_gmt":"2023-10-06T13:47:38","guid":{"rendered":"https:\/\/clmulti.com\/?p=7238"},"modified":"2023-10-06T16:01:13","modified_gmt":"2023-10-06T19:01:13","slug":"inversores-presentaron-al-gobierno-proyecto-de-puerto-oceanico-en-la-paloma","status":"publish","type":"post","link":"https:\/\/clmulti.com\/en\/noticias\/inversores-presentaron-al-gobierno-proyecto-de-puerto-oceanico-en-la-paloma\/","title":{"rendered":"Inversores presentaron al gobierno proyecto de puerto oce\u00e1nico en La Paloma"},"content":{"rendered":"<p class=\"has-medium-font-size\"><strong>La propuesta tiene el objetivo de captar la atenci\u00f3n de buques con mayor capacidad de carga.<\/strong><\/p>\n\n\n\n<p>Un grupo de inversores argentinos y uruguayos quieren llevar adelante una iniciativa privada para construir un puerto oce\u00e1nico en Rocha. La terminal, que ser\u00e1 operada con tecnolog\u00edas verdes, buscar\u00e1 captar la operativa de buques de mayor capacidad de carga.<\/p>\n\n\n\n<p>El proyecto, llamado La Paloma HUB (LPH), ya se present\u00f3 en el Ministerio de Transporte, Presidencia y la Intendencia de Rocha. Adem\u00e1s de la actividad de carga tiene previsto dotar al balneario de un muelle para cruceros y actividades n\u00e1uticas.<\/p>\n\n\n\n<p>La iniciativa supone la construcci\u00f3n de una terminal 100% sustentable en el actual puerto de La Paloma con una profundidad de 18 metros con la que se pretende transformar esa zona del pa\u00eds en un hub de cargas del Mercosur para el transporte de alimentos, granos minerales y energ\u00eda.<\/p>\n\n\n\n<p>Se busca captar la atenci\u00f3n de buques Capsize. Estas embarcaciones tienen una mayor capacidad de carga y son utilizadas b\u00e1sicamente para el transporte de granos. Representan el 9% de la flota de este tipo a nivel mundial. Tienen una capacidad de carga de hasta 110.000 toneladas. Poseen un calado de entre 45 y 50 pies, equivalente 15,2 metros. Son m\u00e1s potentes que los Panamax, con un calado de entre 40 y 42 pies, equivalentes a 12,2 metros y capacidad para 60.000 toneladas.<\/p>\n\n\n\n<p>Los impulsores del proyecto se\u00f1alaron que en un futuro pr\u00f3ximo el volumen de transporte mar\u00edtimo internacional se multiplicar\u00e1 por cuatro, lo que impactar\u00e1 directamente en el calado de los buques que podr\u00e1n transportar hasta 300.000 toneladas por viaje. Por eso indicaron que para Uruguay ser\u00eda clave disponer, a mediano plazo, de una terminal en la que puedan operar buques de gran calado y sobre la que el pa\u00eds tenga \u201csoberan\u00eda plena\u201d.<\/p>\n\n\n\n<p>El proyecto despert\u00f3 inter\u00e9s en grandes compa\u00f1\u00edas internacionales, que ya firmaron cartas de intenci\u00f3n con los inversores comprometiendo su participaci\u00f3n en el desarrollo y operaci\u00f3n una vez que la iniciativa privada sea aprobada.<\/p>\n\n\n\n<p>La propuesta incluye adem\u00e1s un \u00e1rea de actividad portuaria terrestre, localizada fuera de La Paloma, donde se desarrollar\u00e1n actividades log\u00edsticas y operar\u00e1 un pol\u00edgono industrial y una zona franca.<\/p>\n\n\n\n<p>Los promotores aseguraron que la terminal no provocar\u00e1 impacto ambiental o visual negativo que afecte al balneario rochense. El puerto y su operativa tendr\u00e1 dos caras: una de ellas hacia el mar, que estar\u00e1 alejada de la vida costera y de la playa donde la terminal realizar\u00e1 la actividad, y otra hacia el balneario con un muelle de cruceros internacionales y un puerto deportivo.<\/p>\n\n\n\n<p>Seg\u00fan la iniciativa presentada, La Paloma Hub ser\u00e1 un puerto multiprop\u00f3sito que funcionar\u00e1 \u00edntegramente en base a energ\u00edas limpias y que tendr\u00e1 foco en la actividad log\u00edstica vinculada al hidr\u00f3geno verde y combustibles. La propuesta incluso prev\u00e9 la posibilidad de producir hidr\u00f3geno verde en la zona, generando el proceso de desalinizaci\u00f3n del agua de mar para no utilizar agua potable.<\/p>\n\n\n\n<p>Los impulsores pretenden ofrecer soluciones log\u00edsticas que permitan atender la demanda existe en materia de transporte de cargas (graneles s\u00f3lidos y lu\u00edquidos) y disponer de un hub concentrador de minerales estrat\u00e9gicos para la regi\u00f3n (litio, cobre y hierro) a costos significativamente m\u00e1s econ\u00f3micos por la ventaja de contar con una profundidad de 18 metros.<\/p>\n\n\n\n<p>Se prev\u00e9 que La Paloma Hub dispondr\u00e1 de una superficie de 220 hect\u00e1reas dedicadas al funcionamiento de la plataforma portuaria, exactamente el doble del \u00e1rea de la que actualmente posee el puerto de Montevideo.<\/p>\n\n\n\n<p>Fuente: Diario EL OBSERVADOR-Montevideo-Uruguay- 05 de octubre 2023<\/p>","protected":false},"excerpt":{"rendered":"<p>La propuesta tiene el objetivo de captar la atenci\u00f3n de buques con mayor capacidad de carga. Un grupo de inversores&#8230;<\/p>","protected":false},"author":8,"featured_media":7241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"single-fullwidth.php","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-7238","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias"},"_links":{"self":[{"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/posts\/7238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/comments?post=7238"}],"version-history":[{"count":3,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/posts\/7238\/revisions"}],"predecessor-version":[{"id":7257,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/posts\/7238\/revisions\/7257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/media\/7241"}],"wp:attachment":[{"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/media?parent=7238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/categories?post=7238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clmulti.com\/en\/wp-json\/wp\/v2\/tags?post=7238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}